{"id":6236,"date":"2021-02-23T21:03:07","date_gmt":"2021-02-24T00:03:07","guid":{"rendered":"http:\/\/nubesmgzdigital.com.ar\/?p=6236"},"modified":"2021-02-23T21:04:05","modified_gmt":"2021-02-24T00:04:05","slug":"fitur-sera-la-primera-gran-experiencia-de-movilidad-internacional-segura","status":"publish","type":"post","link":"https:\/\/nubesmgzdigital.com.ar\/index.php\/2021\/02\/23\/fitur-sera-la-primera-gran-experiencia-de-movilidad-internacional-segura\/","title":{"rendered":"Fitur ser\u00e1 la primera gran experiencia de movilidad internacional segura"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>Todas las administraciones se unen para celebrar del 19 al 23 de mayo la feria que busca relanzar el Turismo haciendo hincapi\u00e9 en los viajes seguros<\/strong><\/p>\n\n\n\n<p class=\"has-cyan-bluish-gray-color has-black-background-color has-text-color has-background wp-block-paragraph\"><em>Fitur ser\u00e1 un escaparate global para analizar iniciativas como los pasaportes sanitarios, los corredores tur\u00edsticos y las pruebas diagn\u00f3sticas en origen y destino<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Fitur 2021<\/strong>, en su edici\u00f3n especial&nbsp;<em>Tourism is back<\/em>, confirma su celebraci\u00f3n entre los&nbsp;<strong>d\u00edas 19 al 23 de mayo<\/strong>, y ser\u00e1 la primera gran experiencia de movilidad internacional segura en Espa\u00f1a.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">As\u00ed ha lo ha ratificado el Ministerio de Industria, Comercio y Turismo del Gobierno de Espa\u00f1a, tras su reuni\u00f3n, el pasado 19 de febrero, con representantes de IFEMA y de todas las administraciones y organismos implicados en la celebraci\u00f3n de esta gran feria internacional del turismo, que busca relanzar el Turismo a nivel global y consolidar a Espa\u00f1a como un prescriptor de turismo seguro.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La ministra de Industria, Comercio y Turismo,&nbsp;<strong>Reyes Maroto<\/strong>; el presidente del Comit\u00e9 Ejecutivo de IFEMA,&nbsp;<strong>Jos\u00e9 Vicente de los Mozos<\/strong>; el presidente de IBERIA y del Comit\u00e9 Organizador de Fitur,&nbsp;<strong>Javier S\u00e1nchez Prieto<\/strong>; la consejera de Cultura y Turismo de la Comunidad de Madrid<strong>, Marta Rivera de la Cruz<\/strong>, y la delegada de Turismo del Ayuntamiento de Madrid,&nbsp;<strong>Almudena Ma\u00edllo<\/strong>, han confirmado el apoyo necesario para hacer de FITUR la gran plataforma de impulso para el sector del turismo y los viajes, comprometiendo los recursos necesarios para hacer del evento un espacio seguro desde el punto de vista sanitario y ofrecer una ventana digital al mundo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En palabras de la ministra de Industria, Comercio y Turismo,&nbsp;<strong>Reyes Maroto<\/strong>, \u201cla celebraci\u00f3n de Fitur es una buena noticia porque permite mostrar al mundo que Espa\u00f1a es sin\u00f3nimo de un destino de calidad y seguro. Adem\u00e1s, Fitur va a ser un escaparate global para debatir sobre iniciativas como los pasaportes sanitarios, los corredores tur\u00edsticos, las pruebas diagn\u00f3sticas, etc. pero tambi\u00e9n representa un hito para el sector tur\u00edstico que afronta un 2021 con optimismo por la llegada de las vacunas que ofrece un horizonte para la reactivaci\u00f3n del sector\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Una idea sobre la que ha incidido el presidente del Comit\u00e9 Ejecutivo de IFEMA, Jos\u00e9 Vicente de los Mozos, al se\u00f1alar que \u201cvamos a concentrar todos nuestros esfuerzos para blindar la celebraci\u00f3n de una de las principales ferias de turismo del mundo como es Fitur, en cuya convocatoria de mayo tienen puestas sus esperanzas los distintos actores de una industria que necesita acelerar su recuperaci\u00f3n y que se ha revelado ahora m\u00e1s que nunca como gran motor de la econom\u00eda. En IFEMA contamos con los protocolos y las condiciones suficientes para que esta convocatoria se desarrolle bajo los mayores est\u00e1ndares de seguridad sanitaria.\u201d<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En este orden de cosas, y con el objetivo de maximizar la seguridad de todos los asistentes a Fitur y de delimitar un espacio ultra seguro para el desarrollo de la mayor convocatoria de la industria tur\u00edstica mundial, los representantes de IFEMA han explicado que, adem\u00e1s de la obligatoriedad de las pruebas PCR en origen y los test r\u00e1pidos&nbsp;<em>in situ<\/em>, se ha desarrollado un protocolo que re\u00fane todas las medidas necesarias para ordenar el flujo de asistentes y su movilidad; establecer los controles de aforo, las distancias de seguridad, la eliminaci\u00f3n de contacto directo mediante el registro digital, y la incorporaci\u00f3n de las \u00faltimas tecnolog\u00edas para la seguridad sanitaria y el conteo de asistentes, y muy especialmente para la renovaci\u00f3n del aire en pabellones.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En referencia a este \u00faltimo aspecto de la ventilaci\u00f3n, cabe subrayar la atenci\u00f3n que ha prestado a minimizar el riesgo de contagio por v\u00eda a\u00e9rea como son los sistemas de climatizaci\u00f3n. Todos los pabellones de IFEMA est\u00e1n dotados con un sistema de ventilaci\u00f3n que permite garantizar 100% de aire exterior, siendo capaces de renovar todo el aire del pabell\u00f3n en poco m\u00e1s de 20 min, manteniendo en todo momento la temperatura de confort necesaria para el desarrollo de la actividad.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A fecha de hoy, Fitur 2021, que ha sido reconocida por el Gobierno como Acontecimiento de Excepcional Inter\u00e9s P\u00fablico, tiene comercializado el 70% de la superficie reservada en IFEMA, con m\u00e1s de 41.200 metros cuadrados netos.&nbsp;<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/www.ifema.es\/fitur\/noticias\/ministerio-confirma-celebracion-fitur#:~:text=Fitur%20ser%C3%A1%20la%20primera%20gran%20experiencia%20de%20movilidad%20internacional%20segura,-Todas%20las%20administraciones&amp;text=Fitur%202021%2C%20en%20su%20edici%C3%B3n,movilidad%20internacional%20segura%20en%20Espa%C3%B1a.\" target=\"_blank\" rel=\"noopener\"><img loading=\"lazy\" decoding=\"async\" width=\"169\" height=\"52\" src=\"https:\/\/nubesmgzdigital.com.ar\/wp-content\/uploads\/2021\/02\/logo_fitur-1.png\" alt=\"\" class=\"wp-image-6237\"\/><\/a><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Todas las administraciones se unen para celebrar del 19 al 23 de mayo la feria que busca relanzar el Turismo haciendo hincapi\u00e9 en los viajes seguros Fitur ser\u00e1 un escaparate global para analizar iniciativas como los pasaportes sanitarios, los corredores tur\u00edsticos y las pruebas diagn\u00f3sticas en origen y destino Fitur 2021, en su edici\u00f3n especial&nbsp;Tourism [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":6238,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[112],"tags":[],"class_list":["post-6236","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-eventos"],"post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/nubesmgzdigital.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/6236","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nubesmgzdigital.com.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nubesmgzdigital.com.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nubesmgzdigital.com.ar\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/nubesmgzdigital.com.ar\/index.php\/wp-json\/wp\/v2\/comments?post=6236"}],"version-history":[{"count":1,"href":"https:\/\/nubesmgzdigital.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/6236\/revisions"}],"predecessor-version":[{"id":6239,"href":"https:\/\/nubesmgzdigital.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/6236\/revisions\/6239"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nubesmgzdigital.com.ar\/index.php\/wp-json\/wp\/v2\/media\/6238"}],"wp:attachment":[{"href":"https:\/\/nubesmgzdigital.com.ar\/index.php\/wp-json\/wp\/v2\/media?parent=6236"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nubesmgzdigital.com.ar\/index.php\/wp-json\/wp\/v2\/categories?post=6236"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nubesmgzdigital.com.ar\/index.php\/wp-json\/wp\/v2\/tags?post=6236"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}